{"id":603,"count":1,"description":"","link":"https:\/\/sinopotel.com.tr\/bilgi\/tag\/amasya-otel-fiyatlari\/","name":"Amasya otel fiyatlar\u0131","slug":"amasya-otel-fiyatlari","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/sinopotel.com.tr\/bilgi\/wp-json\/wp\/v2\/tags\/603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinopotel.com.tr\/bilgi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/sinopotel.com.tr\/bilgi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/sinopotel.com.tr\/bilgi\/wp-json\/wp\/v2\/posts?tags=603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}